{"id":1394,"date":"2024-10-27T13:48:15","date_gmt":"2024-10-27T13:48:15","guid":{"rendered":"https:\/\/honey-betz.com\/contact\/"},"modified":"2025-12-03T09:01:00","modified_gmt":"2025-12-03T09:01:00","slug":"contatto","status":"publish","type":"page","link":"https:\/\/honey-betz.com\/it\/contatto\/","title":{"rendered":"Contatto"},"content":{"rendered":"<h1>Contatto<\/h1>\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1992-o1\" lang=\"it-IT\" dir=\"ltr\" data-wpcf7-id=\"1992\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/it\/wp-json\/wp\/v2\/pages\/1394#wpcf7-f1992-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"1992\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.0.4\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"it_IT\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1992-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<label> Il tuo nome\n    <input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/> \n<\/label>\n\n<label> Email\n    <input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/> \n<\/label>\n\n<label> Il tuo messaggio\n    <textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea> \n<\/label>\n\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner btn btn-orange rounded-pill btn-zoomin px-4 fw-bold\" type=\"submit\" value=\"Inviare\" \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Contatto<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-builder.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-1394","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Contatto<\/title>\n<meta name=\"description\" content=\"Contattateci per qualsiasi domanda o assistenza. Compilate il modulo e il nostro team di assistenza vi risponder\u00e0 prontamente per risolvere i vostri problemi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/honey-betz.com\/it\/contatto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contatto\" \/>\n<meta property=\"og:description\" content=\"Contattateci per qualsiasi domanda o assistenza. Compilate il modulo e il nostro team di assistenza vi risponder\u00e0 prontamente per risolvere i vostri problemi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/honey-betz.com\/it\/contatto\/\" \/>\n<meta property=\"og:site_name\" content=\"honeybetz\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-03T09:01:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/honey-betz.com\/it\/contatto\/\",\"url\":\"https:\/\/honey-betz.com\/it\/contatto\/\",\"name\":\"Contatto\",\"isPartOf\":{\"@id\":\"https:\/\/honey-betz.com\/it\/#website\"},\"datePublished\":\"2024-10-27T13:48:15+00:00\",\"dateModified\":\"2025-12-03T09:01:00+00:00\",\"description\":\"Contattateci per qualsiasi domanda o assistenza. Compilate il modulo e il nostro team di assistenza vi risponder\u00e0 prontamente per risolvere i vostri problemi.\",\"breadcrumb\":{\"@id\":\"https:\/\/honey-betz.com\/it\/contatto\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/honey-betz.com\/it\/contatto\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/honey-betz.com\/it\/contatto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Honeybetz\",\"item\":\"https:\/\/honey-betz.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contatto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/honey-betz.com\/it\/#website\",\"url\":\"https:\/\/honey-betz.com\/it\/\",\"name\":\"Honeybetz\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/honey-betz.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/honey-betz.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/honey-betz.com\/it\/#organization\",\"name\":\"Honeybetz\",\"url\":\"https:\/\/honey-betz.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/honey-betz.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/honey-betz.com\/wp-content\/uploads\/2025\/08\/80u1FaquEZeR6OUTeJCc.png\",\"contentUrl\":\"https:\/\/honey-betz.com\/wp-content\/uploads\/2025\/08\/80u1FaquEZeR6OUTeJCc.png\",\"width\":85,\"height\":24,\"caption\":\"Honeybetz\"},\"image\":{\"@id\":\"https:\/\/honey-betz.com\/it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contatto","description":"Contattateci per qualsiasi domanda o assistenza. Compilate il modulo e il nostro team di assistenza vi risponder\u00e0 prontamente per risolvere i vostri problemi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/honey-betz.com\/it\/contatto\/","og_locale":"it_IT","og_type":"article","og_title":"Contatto","og_description":"Contattateci per qualsiasi domanda o assistenza. Compilate il modulo e il nostro team di assistenza vi risponder\u00e0 prontamente per risolvere i vostri problemi.","og_url":"https:\/\/honey-betz.com\/it\/contatto\/","og_site_name":"honeybetz","article_modified_time":"2025-12-03T09:01:00+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/honey-betz.com\/it\/contatto\/","url":"https:\/\/honey-betz.com\/it\/contatto\/","name":"Contatto","isPartOf":{"@id":"https:\/\/honey-betz.com\/it\/#website"},"datePublished":"2024-10-27T13:48:15+00:00","dateModified":"2025-12-03T09:01:00+00:00","description":"Contattateci per qualsiasi domanda o assistenza. Compilate il modulo e il nostro team di assistenza vi risponder\u00e0 prontamente per risolvere i vostri problemi.","breadcrumb":{"@id":"https:\/\/honey-betz.com\/it\/contatto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/honey-betz.com\/it\/contatto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/honey-betz.com\/it\/contatto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Honeybetz","item":"https:\/\/honey-betz.com\/it\/"},{"@type":"ListItem","position":2,"name":"Contatto"}]},{"@type":"WebSite","@id":"https:\/\/honey-betz.com\/it\/#website","url":"https:\/\/honey-betz.com\/it\/","name":"Honeybetz","description":"","publisher":{"@id":"https:\/\/honey-betz.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/honey-betz.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/honey-betz.com\/it\/#organization","name":"Honeybetz","url":"https:\/\/honey-betz.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/honey-betz.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/honey-betz.com\/wp-content\/uploads\/2025\/08\/80u1FaquEZeR6OUTeJCc.png","contentUrl":"https:\/\/honey-betz.com\/wp-content\/uploads\/2025\/08\/80u1FaquEZeR6OUTeJCc.png","width":85,"height":24,"caption":"Honeybetz"},"image":{"@id":"https:\/\/honey-betz.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/honey-betz.com\/it\/wp-json\/wp\/v2\/pages\/1394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/honey-betz.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/honey-betz.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/honey-betz.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/honey-betz.com\/it\/wp-json\/wp\/v2\/comments?post=1394"}],"version-history":[{"count":2,"href":"https:\/\/honey-betz.com\/it\/wp-json\/wp\/v2\/pages\/1394\/revisions"}],"predecessor-version":[{"id":1555,"href":"https:\/\/honey-betz.com\/it\/wp-json\/wp\/v2\/pages\/1394\/revisions\/1555"}],"wp:attachment":[{"href":"https:\/\/honey-betz.com\/it\/wp-json\/wp\/v2\/media?parent=1394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}